{"id":1588362,"date":"2020-04-14T00:00:00","date_gmt":"2020-04-14T04:00:00","guid":{"rendered":"https:\/\/divine.ca\/?p=1588362"},"modified":"2020-04-14T16:46:38","modified_gmt":"2020-04-14T20:46:38","slug":"recette-roules-de-laitue-au-porc-et-au-melon-deau","status":"publish","type":"post","link":"https:\/\/divine.ca\/fr\/recette-roules-de-laitue-au-porc-et-au-melon-deau\/","title":{"rendered":"Recette: Roul\u00e9s de laitue au porc et au melon d&#8217;eau"},"content":{"rendered":"<p>Des heures dans la mijoteuse rendent ce porc rehauss\u00e9 de melon d\u2019eau aussi succulent que juteux. La salade de melon d\u2019eau et concombre donne \u00e0 ces roul\u00e9s une touche agr\u00e9ablement croquante, et les graines de s\u00e9same ajoutent leur texture dense en prot\u00e9ines.<\/p>\n<p><em>Donne 4 \u00e0 6 portions<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1594408\" src=\"https:\/\/divine.ca\/wp-content\/uploads\/2018\/06\/Lettuce-Wraps_2018-small72-800x369.jpg\" alt=\"\" width=\"800\" height=\"369\" srcset=\"https:\/\/divine.ca\/wp-content\/uploads\/2018\/06\/Lettuce-Wraps_2018-small72-800x369.jpg 800w, https:\/\/divine.ca\/wp-content\/uploads\/2018\/06\/Lettuce-Wraps_2018-small72-1160x535.jpg 1160w, https:\/\/divine.ca\/wp-content\/uploads\/2018\/06\/Lettuce-Wraps_2018-small72-320x148.jpg 320w, https:\/\/divine.ca\/wp-content\/uploads\/2018\/06\/Lettuce-Wraps_2018-small72-560x258.jpg 560w, https:\/\/divine.ca\/wp-content\/uploads\/2018\/06\/Lettuce-Wraps_2018-small72-rotated.jpg 1495w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2 id=\"ingredients\">Ingr\u00e9dients<\/h2>\n<h3 id=\"porc-barbecue\">Porc barbecue<\/h3>\n<ul>\n<li>1 \u00bd \u00e0 2 lb (680 \u00e0 908 g) de c\u00f4tes de porc rustiques<\/li>\n<li>Sel et poivre du moulin, au go\u00fbt<\/li>\n<li>1\/4 tasse (60 ml) de sauce soya \u00e0 teneur r\u00e9duite de sodium<\/li>\n<li>1\/4 tasse (60 ml) de vinaigre de riz<\/li>\n<li>2 c. \u00e0 table (30 ml) de miel<\/li>\n<li>1 c. \u00e0 table (15 ml) d\u2019huile de s\u00e9same<\/li>\n<li>1 \u00e0 2 c. \u00e0 table (15 \u00e0 30 ml) de sauce gochujang ou sriracha<\/li>\n<li>1 tasse (250 ml) de melon d\u2019eau sans p\u00e9pins, coup\u00e9 en d\u00e9s et r\u00e9duit en pur\u00e9e<\/li>\n<\/ul>\n<h3 id=\"salade-de-melon-deau-et-concombre\">Salade de melon d\u2019eau et concombre<\/h3>\n<ul>\n<li>2 c. \u00e0 th\u00e9 (10 ml) d\u2019huile de s\u00e9same<\/li>\n<li>1 c. \u00e0 table (15 ml) de sauce soya<\/li>\n<li>1 c. \u00e0 table (15 ml) de vinaigre de riz<\/li>\n<li>2 de mini concombres, tranch\u00e9s finement<\/li>\n<li>1 tasse (250 ml) de melon d\u2019eau sans p\u00e9pins, coup\u00e9 en d\u00e9s<\/li>\n<li>Sel au go\u00fbt<\/li>\n<li>2 c. \u00e0 table (30 ml) de graines de s\u00e9same noir<\/li>\n<li>1\/4 tasse (60 ml) de basilic, \u00e9minc\u00e9<\/li>\n<li>1 c. \u00e0 table (15 ml) de menthe, \u00e9minc\u00e9e<\/li>\n<li>2 pommes de laitue Bibb, en feuilles<\/li>\n<\/ul>\n<h2 id=\"preparation\">Pr\u00e9paration<\/h2>\n<ol>\n<li>Saler et poivrer les c\u00f4tes de porc, puis les disposer au fond de la mijoteuse.<\/li>\n<li>Dans un petit bol, combiner la sauce soya, le vinaigre de riz, le miel, l\u2019huile de s\u00e9same, la sauce gochujang (ou sriracha) et la pur\u00e9e de melon d\u2019eau. M\u00e9langer au fouet jusqu\u2019\u00e0 consistance homog\u00e8ne; verser le m\u00e9lange sur les c\u00f4tes. Cuire \u00e0 feu doux 8 \u00e0 10 heures.<\/li>\n<li>Entre temps, commencer \u00e0 pr\u00e9parer la salade en m\u00e9langeant au fouet l\u2019huile de s\u00e9same, la sauce soya et le vinaigre de riz dans un petit bol. Ajouter le concombre et le melon d\u2019eau. M\u00ealer le tout et saler au go\u00fbt. Ajouter les graines de s\u00e9same, le basilic et la menthe, et r\u00e9frig\u00e9rer jusqu\u2019au moment de servir.<\/li>\n<li>Lorsque les c\u00f4tes sont cuites, effilocher la viande \u00e0 la fourchette. Pour assembler les roul\u00e9s de laitue, remplir une feuille de laitue de porc effiloch\u00e9. Garnir de salade de melon d\u2019eau, et ajouter au filet de sauce gochujang ou sriracha si d\u00e9sir\u00e9.<\/li>\n<\/ol>\n<p><em>*Cette recette peut \u00e9galement \u00eatre r\u00e9alis\u00e9e avec des bouts de c\u00f4tes de b\u0153uf.<\/em><\/p>\n<p>Source\u00a0: watermelon.org<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Des heures dans la mijoteuse rendent ce porc rehauss\u00e9 de melon d\u2019eau aussi succulent que juteux. La salade de melon d\u2019eau et concombre donne \u00e0 ces roul\u00e9s une touche agr\u00e9ablement&hellip;<\/div>\n<div class=\"post-more\"><a href=\"https:\/\/divine.ca\/fr\/recette-roules-de-laitue-au-porc-et-au-melon-deau\/\" class=\"button button-primary button-effect\"><span>Lire l&#039;Article<\/span><span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span><\/a><\/div>\n","protected":false},"author":19,"featured_media":1594408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[129],"tags":[665,5102,4979,5103,124,4931],"powerkit_post_featured":[],"class_list":{"0":"post-1588362","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-bouffe","8":"tag-bouffe","9":"tag-laitue","10":"tag-melon-deau-fr","11":"tag-porc-fr","12":"tag-recette","13":"tag-salade-fr"},"_links":{"self":[{"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/posts\/1588362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/comments?post=1588362"}],"version-history":[{"count":0,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/posts\/1588362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/media\/1594408"}],"wp:attachment":[{"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/media?parent=1588362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/categories?post=1588362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/tags?post=1588362"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=1588362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}