{"id":1586802,"date":"2017-08-11T00:00:00","date_gmt":"2017-08-11T04:00:00","guid":{"rendered":"https:\/\/divine.ca\/?p=1586802"},"modified":"2020-09-18T20:51:15","modified_gmt":"2020-09-19T00:51:15","slug":"soins-solaires-choisir-son-camp","status":"publish","type":"post","link":"https:\/\/divine.ca\/fr\/soins-solaires-choisir-son-camp\/","title":{"rendered":"Soins solaires: choisir son camp"},"content":{"rendered":"<p class=\"pk-dropcap pk-dropcap-borders\" style=\"text-align: justify;\">Quel est le meilleur \u00e9cran solaire? Chaque marque vous dira que c\u2019est le sien. Donc, plut\u00f4t que de vous arracher les cheveux \u00e0 tenter de trouver une v\u00e9rit\u00e9 absolue, on vous propose ici de comprendre les marques pour mieux <a href=\"https:\/\/divine.ca\/fr\/vacances-a-la-plage-quoi-mettre-dans-sa-valise-pour-ne-rien-oublier\/\">utiliser leurs soins<\/a>. Voici donc les fondements et la philosophie de trois labels parmi les plus populaires.<\/p>\n<p style=\"text-align: justify;\"><strong>Ombrelle \u00e0 la guerre contre les\u00a0UVA<br \/>\n<\/strong>Un entrepreneur montr\u00e9alais l\u2019a fond\u00e9e en 1990, en \u00e9troite collaboration avec des dermatologues. Ombrelle est alors devenue pionni\u00e8re dans la lutte contre les UVA. Depuis, elle se fait un devoir de sensibiliser les consommateurs \u00e0 l\u2019importance de se prot\u00e9ger du soleil. Non seulement ses lotions sont accessibles (environ 20 $ la bouteille), mais elles offrent une exp\u00e9rience d\u2019application tellement agr\u00e9able qu\u2019elle nous incite \u00e0 r\u00e9appliquer.<\/p>\n<p style=\"text-align: justify;\">Ombrelle nous offre cette lotion pour le corps inspir\u00e9e par sa formule fluide pour le visage. On l\u2019applique facilement et, illico absorb\u00e9e par la peau, elle ne laisse aucune trace blanche. Cela, bien s\u00fbr en plus de renfermer une\u00a0protection UVA qu\u2019on nous promet remarquable. <em>Lotion extra-l\u00e9g\u00e8re pour le corps Ultra-Light Advanced FPS 50+ par <\/em><a href=\"http:\/\/www.garnier.ca\/fr-ca\/protection-solaire\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><em>Ombrelle<\/em><\/strong><\/a><em>, 19,99 $ en pharmacie.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1599571 size-full\" src=\"https:\/\/divine.ca\/wp-content\/uploads\/2017\/08\/Ombrelle-Sunscreen.jpg\" alt=\"Soins solaires\" width=\"450\" height=\"600\" srcset=\"https:\/\/divine.ca\/wp-content\/uploads\/2017\/08\/Ombrelle-Sunscreen.jpg 450w, https:\/\/divine.ca\/wp-content\/uploads\/2017\/08\/Ombrelle-Sunscreen-320x427.jpg 320w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: left;\"><strong>Saviez-vous que:\u00a0<\/strong>Un nouveau logo nous permet maintenant de rep\u00e9rer les produits qui contiennent une concentration d\u2019au moins 30 % d\u2019ingr\u00e9dients prot\u00e9geant contre les UVA, v\u00e9rification faite par Sant\u00e9 Canada. Surveillez le cercle!<\/p>\n<p style=\"text-align: justify;\"><strong>Esthederm et la th\u00e9orie de l\u2019adaptation<br \/>\n<\/strong>Chez la marque fran\u00e7aise, l\u2019adaptation naturelle de la peau au soleil est au centre des formulations. Ces derni\u00e8res, elles sont pens\u00e9es afin de prot\u00e9ger contre les UVB et UVA, de pr\u00e9server l\u2019ADN et de pr\u00e9venir le vieillissement pr\u00e9matur\u00e9 de la peau, cela tout en, attention: optimisant l\u2019environnement \u00e9nerg\u00e9tique cellulaire. Ainsi, la peau se prot\u00e8ge en bronzant, et elle en vient \u00e0 mieux s\u2019adapter au soleil. Ici, on oublie aussi les indices FPS: ce sont des petits soleils qui nous indiquent le degr\u00e9 de protection.<\/p>\n<p style=\"text-align: justify;\">Le produit de la saison chez Esthederm, c\u2019est ce lait en spray. On vaporise d\u2019une main, puis on \u00e9tend la lotion a\u00e9rienne de l\u2019autre. Le format de sa bouteille est id\u00e9al, et sa texture l\u2019est tout autant. Le soin prot\u00e8ge la peau tout en activant le bronzage, renfermant aussi de l\u2019eau cellulaire, composante cl\u00e9 de la marque, celle qui stimule les cellules. <em>Soin bronzant Adaptasun Spray Lact\u00e9 par <\/em><a href=\"http:\/\/esthederm.ca\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><em>Esthederm<\/em><\/strong><\/a><em>, offert en protection 2 et 3 soleils, 69 $ en institut et en ligne.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1602308 size-medium\" src=\"https:\/\/divine.ca\/wp-content\/uploads\/2017\/08\/solaire_adaptasun_lait_3soleils-1080x1080-1-800x800.jpg\" alt=\"Soin Solaire\" width=\"800\" height=\"800\" srcset=\"https:\/\/divine.ca\/wp-content\/uploads\/2017\/08\/solaire_adaptasun_lait_3soleils-1080x1080-1-800x800.jpg 800w, https:\/\/divine.ca\/wp-content\/uploads\/2017\/08\/solaire_adaptasun_lait_3soleils-1080x1080-1-80x80.jpg 80w, https:\/\/divine.ca\/wp-content\/uploads\/2017\/08\/solaire_adaptasun_lait_3soleils-1080x1080-1-320x320.jpg 320w, https:\/\/divine.ca\/wp-content\/uploads\/2017\/08\/solaire_adaptasun_lait_3soleils-1080x1080-1-560x560.jpg 560w, https:\/\/divine.ca\/wp-content\/uploads\/2017\/08\/solaire_adaptasun_lait_3soleils-1080x1080-1-90x90.jpg 90w, https:\/\/divine.ca\/wp-content\/uploads\/2017\/08\/solaire_adaptasun_lait_3soleils-1080x1080-1.jpg 1080w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>Saviez-vous que: <\/strong>Notre \u00e9cran solaire, on doit l\u2019appliquer au moins 20 minutes avant de sortir \u00e0 l\u2019ext\u00e9rieur\u00a0(environ l\u2019\u00e9quivalent de deux cuill\u00e8res \u00e0 soupe pour tout le corps d\u2019un adulte), puis r\u00e9appliquer au moins toutes les deux heures.<\/p>\n<p style=\"text-align: justify;\"><strong>Av\u00e8ne \u00e0 la rescousse des peaux sensibles<br \/>\n<\/strong>La marque, celle de l\u2019eau thermale, associe s\u00e9curit\u00e9 et confort afin de convenir aux plus fragiles des peaux. Elle utilise des \u00e9crans en partie ou compl\u00e8tement min\u00e9raux, pour pr\u00e9venir les r\u00e9actions cutan\u00e9es caus\u00e9es par le soleil, ces derni\u00e8res \u00e9tant mari\u00e9es \u00e0 un antioxydant (nomm\u00e9 Pr\u00e9tocoph\u00e9ryl, pour les curieux) et \u00e0, roulement de tambour\u2026 l\u2019eau thermale Av\u00e8ne. Cette derni\u00e8re permet \u00e0 la peau de retrouver son \u00e9quilibre en restaurant sa barri\u00e8re \u00e9pidermique.<\/p>\n<p style=\"text-align: justify;\">Ce lait pour le corps offre une protection \u00e0 large spectre et, ET il s\u00e8che particuli\u00e8rement rapidement. \u00c0 l\u2019application il est aussi compl\u00e8tement inapparent. Ici, l\u2019\u00e9cran min\u00e9ral est associ\u00e9 \u00e0 des\u00a0filtres solaires chimiques. Parmi les nouveaut\u00e9s on retrouve aussi un lait compl\u00e8tement min\u00e9ral, encore plus s\u00e9curitaire mais moins translucide, celui-ci \u00e9tant id\u00e9al pour les plus petits. <em>Lait haute protection FPS 50+ par <\/em><a href=\"http:\/\/www.eau-thermale-avene.ca\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><em>Av\u00e8ne<\/em><\/strong><\/a><em>, 29,50 $ en pharmacie.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1599575\" src=\"https:\/\/divine.ca\/wp-content\/uploads\/2017\/08\/Avene-Sunscreen-1.jpg\" alt=\"\" width=\"184\" height=\"413\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1602300\" src=\"https:\/\/divine.ca\/wp-content\/uploads\/2017\/08\/Avene-Sunscreen.jpg\" alt=\"\" width=\"229\" height=\"423\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Saviez-vous que: <\/strong>Afin d\u2019\u00e9viter un faux sentiment de s\u00e9curit\u00e9 chez le consommateur, Sant\u00e9 Canada exige maintenant que l\u2019indice des \u00e9crans solaires au FPS sup\u00e9rieur \u00e0 50 soit pr\u00e9sent\u00e9 ainsi sur l\u2019emballage: FPS 50+.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Quel est le meilleur \u00e9cran solaire? Chaque marque vous dira que c\u2019est le sien. Donc, plut\u00f4t que de vous arracher les cheveux \u00e0 tenter de trouver une v\u00e9rit\u00e9 absolue, on&hellip;<\/div>\n<div class=\"post-more\"><a href=\"https:\/\/divine.ca\/fr\/soins-solaires-choisir-son-camp\/\" class=\"button button-primary button-effect\"><span>Lire l&#039;Article<\/span><span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span><\/a><\/div>\n","protected":false},"author":32,"featured_media":1599579,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[127],"tags":[1128,2166,7527,4525,7528],"powerkit_post_featured":[],"class_list":{"0":"post-1586802","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mode","8":"tag-avene","9":"tag-esthederm","10":"tag-ombrelle-fr","11":"tag-soins-de-la-peau-fr","12":"tag-soins-solaires-fr"},"_links":{"self":[{"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/posts\/1586802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/comments?post=1586802"}],"version-history":[{"count":2,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/posts\/1586802\/revisions"}],"predecessor-version":[{"id":1602311,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/posts\/1586802\/revisions\/1602311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/media\/1599579"}],"wp:attachment":[{"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/media?parent=1586802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/categories?post=1586802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/tags?post=1586802"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=1586802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}