{"id":1578587,"date":"2020-01-30T17:29:49","date_gmt":"2020-01-30T22:29:49","guid":{"rendered":"https:\/\/divine.ca\/?p=1578587"},"modified":"2020-04-09T14:33:20","modified_gmt":"2020-04-09T18:33:20","slug":"recettes-du-super-bowl-ailes-de-dindon-buffalo","status":"publish","type":"post","link":"https:\/\/divine.ca\/fr\/recettes-du-super-bowl-ailes-de-dindon-buffalo\/","title":{"rendered":"Recettes du Super Bowl: Ailes De Dindon Buffalo"},"content":{"rendered":"<p>Si vous servez un tas de personnes affam\u00e9es le dimanche du <a href=\"https:\/\/divine.ca\/fr\/recettes-du-super-bowl-trempette-7-etages-au-chimichurri\/\">Super Bowl<\/a>, ces ailes de dinde Buffalo seront parfaites.\u00a0\u00a0Avec seulement 15 minutes de temps de pr\u00e9paration, il n&#8217;est pas n\u00e9cessaire de stresser!\u00a0\u00a0C&#8217;est une recette facile \u00e0 faire si vous avez des invit\u00e9s qui s\u2019ajoutent \u00e0 la derni\u00e8re minute. Lisa Dawn Bolton a cr\u00e9\u00e9 cette version de la recette classique de comfort food!<\/p>\n<p><strong>Portions:<\/strong> 1-2<\/p>\n<p><strong>Temps de pr\u00e9paration:<\/strong> 15 mins<\/p>\n<p><strong>Temps de cuisson:<\/strong> 90 mins<\/p>\n<h3 id=\"ingredients\"><strong>Ingr\u00e9dients:<\/strong><\/h3>\n<p>-4 ailes de dindon (s\u00e9par\u00e9s les pilons d\u2019aile des ailerons)<\/p>\n<p>-2 c. \u00e0 soupe d\u2019huile d\u2019avocat (ou une autre huile avec une temp\u00e9rature critique \u00e9lev\u00e9e, telle que l\u2019huile de canola)<\/p>\n<p>-\u00bd tasse de beurre<\/p>\n<p>-1 tasse de sauce piquante aux piments de Cayenne<\/p>\n<p>-Cr\u00e8me sure, trempette au fromage bleu ou trempette ranch en accompagnement (optionnelle)<\/p>\n<p>-C\u00e9leri en garniture<\/p>\n<h3 id=\"preparation\"><strong>Pr\u00e9paration :<\/strong><\/h3>\n<p>1) Pr\u00e9chauffer le four \u00e0 350 degr\u00e9s Fahrenheit (180 degr\u00e9s Celsius).<\/p>\n<p>2) Enlever les ailes de l\u2019emballage et s\u00e9parer les pilons d\u2019aile des ailerons. Badigeonner une grille m\u00e9tallique avec l\u2019huile et la placer sur une plaque de cuisson (recouvrir la plaque avec du papier d\u2019aluminium pour faciliter le nettoyage). Verser environ une demi-tasse d\u2019eau dans la plaque de cuisson. \u00c9ponger le plus possible les ailes avec un essuie-tout et les placer sur la grille en v\u00e9rifiant bien qu\u2019elles ne se touchent pas. Recouvrir d\u2019une feuille d\u2019aluminium pli\u00e9 en forme de tente. Cuire au four pendant 1 heure. Enlever la feuille d\u2019aluminium et continuer la cuisson jusqu\u2019\u00e0 ce que les ailes atteignent une temp\u00e9rature interne de 165 degr\u00e9s Fahrenheit (74 degr\u00e9s Celsius), environ 30 \u00e0 45 minutes suppl\u00e9mentaires.<\/p>\n<p>3) Pendant que les ailes cuisent, pr\u00e9parer la sauce Buffalo. Dans une petite casserole, \u00e0 feu moyen, faire fondre le beurre avec la sauce piquante, en remuant fr\u00e9quemment jusqu\u2019\u00e0 ce que le m\u00e9lange soit homog\u00e8ne.<\/p>\n<p>4) Lorsque les ailes sont pr\u00eates, les arroser avec la sauce ou les y plonger. Servir avec des \u00e0-c\u00f4t\u00e9s rafra\u00eechissants comme le c\u00e9leri, accompagn\u00e9 de cr\u00e8me sure ou d\u2019une trempette au fromage bleu ou ranch. Servir le reste de la sauce en accompagnement.<\/p>\n<p>Recette gracieuset\u00e9 de\u00a0<a href=\"https:\/\/www.dindoncanadien.ca\/\" target=\"_blank\" rel=\"noopener\">Pensez Dindon<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Si vous servez un tas de personnes affam\u00e9es le dimanche du Super Bowl, ces ailes de dinde Buffalo seront parfaites.\u00a0\u00a0Avec seulement 15 minutes de temps de pr\u00e9paration, il n&#8217;est pas&hellip;<\/div>\n<div class=\"post-more\"><a href=\"https:\/\/divine.ca\/fr\/recettes-du-super-bowl-ailes-de-dindon-buffalo\/\" class=\"button button-primary button-effect\"><span>Lire l&#039;Article<\/span><span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span><\/a><\/div>\n","protected":false},"author":19,"featured_media":1578588,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[129],"tags":[934,125,932],"powerkit_post_featured":[],"class_list":["post-1578587","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bouffe","tag-ailes-de-dindon","tag-recettes","tag-recettes-du-super-bowl"],"_links":{"self":[{"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/posts\/1578587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/comments?post=1578587"}],"version-history":[{"count":0,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/posts\/1578587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/media\/1578588"}],"wp:attachment":[{"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/media?parent=1578587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/categories?post=1578587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/tags?post=1578587"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/divine.ca\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=1578587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}